{"id":2667,"date":"2018-10-20T14:09:45","date_gmt":"2018-10-20T17:09:45","guid":{"rendered":"http:\/\/www.netqual.com.ar\/netqual\/?p=2667"},"modified":"2022-07-01T17:39:19","modified_gmt":"2022-07-01T20:39:19","slug":"seguridad-informatica","status":"publish","type":"post","link":"https:\/\/www.netqual.com.ar\/netqual\/seguridad-informatica\/","title":{"rendered":"Seguridad Inform\u00e1tica. Sobre mitos y verdades\u2026"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>Una visi\u00f3n sobre el impacto del Ransomware en Argentina y Seguridad Inform\u00e1tica. <strong>Netqual es Partner de ESET en Argentina y lo integra a sus plataformas de Gesti\u00f3n de Infraestructura.<\/strong><\/p>\n<h2>WannaCry, el inicio<\/h2>\n<p>El mundo fue asolado por el WannaCry, gusano que ataca una vulnerabilidad de Windows empleando un \u201cexploit\u201d denominado \u201cEternalBlue\u201d, supuestamente desarrollado por la NSA, agencia de seguridad nacional de USA y filtrado por un grupo de hackers. Su accionar es codificar criptogr\u00e1ficamente la informaci\u00f3n y pedir un rescate a cambio de la clave (llamativamente, bajo por cierto, unos trescientos d\u00f3lares).<\/p>\n<p>De este ransomware del cual se ha hablado y escrito profusamente, desde diversas \u00f3pticas y entretejiendo todos los niveles de conspiraciones posibles, nos ha dejado algunas ense\u00f1anzas, que por lo imprecisas, no dejan de ser inquietantes:<\/p>\n<ul>\n<li>La guerra por el control de la informaci\u00f3n y dispositivos conectados evidentemente existe.<\/li>\n<li>La guerra psicol\u00f3gica medi\u00e1tica, se ha extendido al mundo virtual.<\/li>\n<li>Es dif\u00edcil diferenciar la realidad (y sus profundos motivos), de la fantas\u00eda que tambi\u00e9n tiene sus profundas motivaciones.<\/li>\n<\/ul>\n<p>Lo que se ha dicho es novelesco y escapa a nuestra capacidad interpretativa o de asombro.<\/p>\n<p>Accionar de pa\u00edses con potencial nuclear, agencias de inteligencia, vulnerabilidades usadas por agencias de seguridad para espiar a la gente&#8230; estupidez de grandes empresas que no se cuidaron de esta vulnerabilidad\u2026 todo es posible. Ante la incertidumbre, vamos a los hechos por nosotros constatados.<\/p>\n<h2>\u00bfQu\u00e9 pas\u00f3 en Argentina?<\/h2>\n<p>La tasa de incidencia de este Ransoware en nuestros clientes, en Argentina fue: 0%.<\/p>\n<p>Repito, hablamos del universo acotado de nuestros clientes y en nuestra \u00e1rea. Esto no quiere decir que el ransomware no haya transitado por nuestro pa\u00eds y que no haya afectado a nadie. De hecho hubo muchas empresas afectadas en todo el mundo.<\/p>\n<p>Por lo que comentaron expertos, el virus era poco avanzado, aunque llamaba la atenci\u00f3n el buen dise\u00f1o de su mecanismo de gusano.<\/p>\n<p>Hace unos meses hubo una oleada de los ransomwares: Locky y Wallet. Esa vez circularon, sin repercusi\u00f3n en la prensa. Ambos virus piden rescate por algunos miles de d\u00f3lares, a cambio de la clave para desencriptar la informaci\u00f3n.<\/p>\n<p>En esos casos, el 20% de nuestros clientes fuero afectados en forma directa, con distintos grados de da\u00f1o. L\u00f3gicamente, el da\u00f1o depend\u00eda directamente del nivel de seguridad que dispon\u00edan y casi siempre se requiere de la \u201ccomplicidad inocente\u201d de quien hace \u201cclick\u201d donde no se debe.<\/p>\n<p>Alg\u00fan cliente estuvo al borde del colapso nervioso y quer\u00eda pagar rescate, algo que recomendamos no hacer.<\/p>\n<h2>El Ransomware vino para quedarse<\/h2>\n<p>El ramsomware en todas sus formas EXISTE. Desconocemos quien lo genera y los verdaderos motivos que pueden estar detr\u00e1s de cada ataque, pero existen.<\/p>\n<p>Cada empresa Pyme de nuestro pa\u00eds, sufre un promedio de entre 400 y 600 ataques en el a\u00f1o. La mayor\u00eda ni se entera (cuando est\u00e1n protegidas). Estas son nuestras estad\u00edsticas.<\/p>\n<p>Casi todos estos ataques son de tipo rob\u00f3tico. Son como ladrones oportunistas que pasan por la calle y observan la casa para ver si los due\u00f1os salieron, si la puerta est\u00e1 abierta, si la ventana est\u00e1 cerca del nivel de piso, si el fondo de la casa linda con un bald\u00edo&#8230; Buscan debilidades y muchos se basan en ingenier\u00eda social (cuento del t\u00edo) con mayor o menor grado de refinaci\u00f3n para que alg\u00fan incauto haga \u201cclick\u201d.<\/p>\n<h2>\u00bfQu\u00e9 hacer?<\/h2>\n<p>Todo depende del presupuesto y del da\u00f1o que nos pueden hacer.<\/p>\n<p>Mi t\u00edo cerrajero, sab\u00eda que el costo de la cerradura que alguien estaba dispuesto a comprar estaba en funci\u00f3n de lo que ten\u00eda que proteger.<\/p>\n<p>Hoy en d\u00eda, perder informaci\u00f3n cr\u00edtica y sufrir un da\u00f1o en los sistemas, aunque no haya informaci\u00f3n especialmente valiosa para alguien, significa tiempo y el tiempo es dinero.<\/p>\n<p>Es el tiempo que se detiene nuestra actividad, sumado al tiempo que tardamos en reconstruir la informaci\u00f3n, sumado al extra que tendremos que pagar por un servicio para reparar, restaurar y atemperar da\u00f1os en una Pyme de 10 personas, que tenga que parar 5 d\u00edas, algo m\u00ednimo si no est\u00e1 protegido y suponiendo que tiene respaldos de informaci\u00f3n no mayores a una semana, puede perder:<\/p>\n<p>Sueldos ociosos: $ 70.000<br \/>\nServicios Inform\u00e1ticos extras: $ 30.000<br \/>\nP\u00e9rdida de ventas depender\u00e1 del negocio\u2026 pero m\u00ednimamente las ventas deben cubrir los sueldos, as\u00ed que de margen establecemos: $ 80.000<\/p>\n<p>Hasta aqu\u00ed: $ 180.000; sin contar da\u00f1os a la imagen de la empresa ni afecciones mayores.<\/p>\n<p>Digamos que es un an\u00e1lisis m\u00ednimo y b\u00e1sico y va a depender de cada actividad en particular, pero son valores importantes.<\/p>\n<p>Digamos que ni siquiera imaginamos un gusano que sea capaz de robar sus claves bancarias\u2026 y estamos suponiendo que el ataque no afect\u00f3 a los respaldos de informaci\u00f3n.<\/p>\n<p>Aclaramos que la nota fue hecha en Octubre 2018, con un d\u00f3lar a $ 37&#8230; que quede como documento de nuestra incurable \u00abinflaci\u00f3n\u00bb.<\/p>\n<h2>Implementar SEGURIDAD en todos los niveles<\/h2>\n<p>La seguridad es un conjunto de elementos, acciones y procedimientos, que d\u00eda a d\u00eda se deben implementar, mantener y actualizar en toda red de datos.<br \/>\nM\u00ednimamente esto implica:<\/p>\n<ul>\n<li>Controlar el acceso a dispositivos cr\u00edticos (remota, local o f\u00edsicamente).<\/li>\n<li>Disponer de Firewall y reglas generales de acceso.<\/li>\n<li>Disponer de Proxy, a los efectos de controlar acceso a lugares no deseados.<\/li>\n<li>Mantener todo el software y sistemas actualizados. Dejar de usar software discontinuado.<\/li>\n<li>Disponer de una estructura de redes virtuales, que acote el tipo y la prioridad de tr\u00e1fico de redes a distintos sectores l\u00f3gicos de la red y servidores.<\/li>\n<li>Disponer de pol\u00edticas de seguridad por usuario que acote el accionar del mismo. Es el error cuando hay muchos usuarios administradores y un virus entra\u2026 con esos privilegios.<\/li>\n<li>Establecer pol\u00edticas antispam, dentro de lo posible, que minimice la llegada de emails con posible contenido malicioso.<\/li>\n<li>Establecer pol\u00edticas de resguardos de informaci\u00f3n autom\u00e1tica y con criterios incrementales, que permita \u201cvolver a un punto seguro\u201d de ser necesario.<\/li>\n<li>Establecer criterios de retorno de un desastre permitiendo restablecer los sistemas en los servidores en un m\u00ednimo tiempo.<\/li>\n<li>Educar a los usuarios a los efectos que entiendan los peligros de acceder a ciertos sitios y de hacer \u201cclick\u201d en un lugar incorrecto.<\/li>\n<li>Disponer de un sistema de seguridad integral (ya no el viejo \u201cantivirus\u201d) que observe el malware en todas sus formas y que act\u00fae de manera centralizada.<\/li>\n<li>Disponer de herramientas diagn\u00f3sticas que permitan r\u00e1pidamente detectar, qu\u00e9 es lo que est\u00e1 ocurriendo.<\/li>\n<\/ul>\n<p>Cumpliendo con estos preceptos, es probable que permanezca indemne ante muchos ataques, salvo aquellos muy virulentos o que est\u00e9n especialmente dirigidos a su Empresa.<\/p>\n<p>Aunque recuerde que para sufrir un ataque dirigido, debe poseer informaci\u00f3n extremadamente valiosa para alguien. Ante estas situaciones hay que aplicar criterios de seguridad a la medida, adem\u00e1s de lo que planteamos anteriormente.<\/p>\n<p>Si se aplicaron todos estos criterios, y algo ocurriera, el da\u00f1o suele circunscribirse a alguna terminal, \u00f3 a algunos archivos \u00f3 en el peor de los casos a alg\u00fan servidor.<\/p>\n<p>Es importante tomar conciencia. Muchas veces se evita pagar por un sistema de seguridad integral, cuando su costo es apenas una fracci\u00f3n al a\u00f1o de lo que perder\u00edamos ante la ocurrencia de un evento. \u00cddem con el hecho de llevar correctamente las actualizaciones de software.<\/p>\n<p>Tenga presente que nadie trabaja gratis. Los \u201cantivirus gratuitos\u201d son versiones reducidas, que buscan que se compre una licencia paga a cambio de una mejor prestaci\u00f3n \u00f3 en el peor de los casos pueden ser otras cosas.<\/p>\n<p>No cometan el error de asociar el concepto de software de c\u00f3digo abierto (como un Linux) a un antivirus gratuito. El antivirus gratuito, no s\u00f3lo no protege correctamente, sino que genera la falsa sensaci\u00f3n de estar protegidos.<\/p>\n<p>Es hora de tomar conciencia y tomar a la seguridad inform\u00e1tica, seriamente y sin paranoias; s\u00f3lo trabajando en forma profesional, correcta&#8230; y con consultores profesionales.<\/p>\n<p>Estamos a su disposici\u00f3n:<\/p>\n<p><a href=\"http:\/\/www.netqual.com.ar\/netqual\/partner-view\/eset\/\">http:\/\/www.netqual.com.ar\/netqual\/partner-view\/eset\/<\/a><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"G7ukXI5CoG\"><p><a href=\"https:\/\/www.netqual.com.ar\/netqual\/contacto\/\">CONTACTO<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abCONTACTO\u00bb \u2014 NetQual SRL\" src=\"https:\/\/www.netqual.com.ar\/netqual\/contacto\/embed\/#?secret=G7ukXI5CoG\" data-secret=\"G7ukXI5CoG\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><a href=\"https:\/\/www.eset.com\/\">https:\/\/www.eset.com\/<\/a><\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>NetQual con sus servicios de Gesti\u00f3n, trata integralmente la seguridad, combinando t\u00e9cnicas y con socios como ESET que suman investigaci\u00f3n y desarrollo.<\/p>\n","protected":false},"author":3,"featured_media":2207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22,10,13],"tags":[246,64],"_links":{"self":[{"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/posts\/2667"}],"collection":[{"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/comments?post=2667"}],"version-history":[{"count":4,"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/posts\/2667\/revisions"}],"predecessor-version":[{"id":11003,"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/posts\/2667\/revisions\/11003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/media\/2207"}],"wp:attachment":[{"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/media?parent=2667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/categories?post=2667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netqual.com.ar\/netqual\/wp-json\/wp\/v2\/tags?post=2667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}